{"id":7964,"date":"2020-08-25T09:00:09","date_gmt":"2020-08-25T07:00:09","guid":{"rendered":"http:\/\/www.blogdeasisa.es\/?p=7964"},"modified":"2020-08-18T17:32:37","modified_gmt":"2020-08-18T15:32:37","slug":"ataxia-en-gatos-que-es-y-como-se-desarrolla-esta-enfermedad","status":"publish","type":"post","link":"\/blog\/salud\/ataxia-en-gatos-que-es-y-como-se-desarrolla-esta-enfermedad\/","title":{"rendered":"Ataxia en gatos: qu\u00e9 es y c\u00f3mo se desarrolla esta enfermedad"},"content":{"rendered":"<p>Nuestras mascotas, al igual que nosotros, sufren<strong> <a href=\"\/\/salud\/las-infecciones-que-transmiten-las-mascotas\/\" target=\"_blank\" rel=\"noopener noreferrer\">enfermedades o infecciones<\/a><\/strong> que son necesarias atender por su seguridad. Por ello, <strong>tener un <a href=\"\/\/corporativo\/seguro-para-mascotas\/\" target=\"_blank\" rel=\"noopener noreferrer\">seguro<\/a> para los cuidados m\u00e9dicos puede llegar a salvar la vida<\/strong> de tu mascota. La <strong>ataxia<\/strong>, por ejemplo, es una de las enfermedades m\u00e1s comunes en gatos y de la que probablemente hayas o\u00eddo hablar, pero \u00bfen qu\u00e9 consiste esta enfermedad?\u00a0<\/p>\n<h2><strong>\u00bfQu\u00e9 es la ataxia? <\/strong><\/h2>\n<p>La <strong>ataxia es consecuencia de la falta de coordinaci\u00f3n, de equilibrio y de precisi\u00f3n<\/strong> en los movimientos de nuestras mascotas. Es, en definitiva, un s\u00edntoma de una enfermedad que <strong>afecta al sistema nervioso del gato<\/strong>. Afecta a la posici\u00f3n del cuerpo y, sobre todo, a la cabeza y a las extremidades. Por tanto, esta afecci\u00f3n se da cuando se produce un problema o una lesi\u00f3n en alguna de las \u00e1reas que controlan los movimientos y por ello, la ataxia es m\u00e1s considerada como un s\u00edntoma m\u00e1s que como una enfermedad.\u00a0<\/p>\n<h2><strong>Tipos de ataxia<\/strong><\/h2>\n<p>La La ataxia puede ser dividida en <strong>tres tipos en funci\u00f3n del \u00e1rea<\/strong> al que afecta esta enfermedad:<\/p>\n<ol>\n<li><strong>Cerebral<\/strong> en la que el cerebelo se ve afectado debilitando el equilibrio y la coordinaci\u00f3n de los movimientos.<\/li>\n<li><strong>Vestibular<\/strong>, consecuencia de una afecci\u00f3n en el o\u00eddo medio-interno o en algunos nervios que conectan el o\u00eddo con el cerebro.<\/li>\n<li><strong>Sensorial <\/strong>en la que el cerebro, medula espinal o nervios perif\u00e9ricos sufren problemas.<\/li>\n<\/ol>\n<h2><strong>Causas de la <\/strong><strong>ataxia<\/strong><\/h2>\n<p>Las causas de esta enfermedad tan com\u00fan en gatos pueden provenir de un accidente, envenenamiento o incluso problemas con la dieta. Otras de las causas pueden ser:<\/p>\n<ol>\n<li><strong>Una lesi\u00f3n<\/strong> en uno de los tres sistemas antes comentados (vestibular, sensorial y cerebelo).<\/li>\n<li>Afecciones en el <strong>sistema nervioso<\/strong>.<\/li>\n<li>Debilidad causada por una <strong>mala alimentaci\u00f3n<\/strong> que puede provocar anemia.<\/li>\n<li><strong>Problemas musculares<\/strong> o de huesos y articulaciones.<\/li>\n<\/ol>\n<h2><strong>\u00bfCu\u00e1les son los s\u00edntomas de la ataxia?<\/strong><\/h2>\n<p>En la <strong>ataxia la sintomatolog\u00eda es muy variada<\/strong>. Seg\u00fan el tipo y la causa de la ataxia, algunos de los s\u00edntomas variar\u00e1n, pero los m\u00e1s caracter\u00edsticos y los que m\u00e1s se suelen presentar son:<\/p>\n<ul>\n<li>Descoordinaci\u00f3n.<\/li>\n<li>Desorientaci\u00f3n.<\/li>\n<li>Debilidad.\u00a0<\/li>\n<li>Temblores.\u00a0<\/li>\n<li>P\u00e9rdida de equilibrio.<\/li>\n<li>Dificultad para moverse, para comer y para orinar y defecar.<\/li>\n<li>Estr\u00e9s y maullidos constantes.<\/li>\n<\/ul>\n<p>Es de vital importancia que, ante cualquiera de estos s\u00edntomas, <strong>acudamos al veterinario<\/strong> para que pueda ser evaluada nuestra mascota y pueda ser sometido a un tratamiento r\u00e1pidamente.<\/p>\n<blockquote>\n<p><strong>Recuerda: <\/strong><\/p>\n<ul>\n<li>La ataxia es una de las enfermedades m\u00e1s comunes en gatos.<\/li>\n<li>Es considerada m\u00e1s como un s\u00edntoma que como una patolog\u00eda.<\/li>\n<li>La descoordinaci\u00f3n de movimientos y la p\u00e9rdida de equilibrio son algunos de los s\u00edntomas que har\u00e1n saltar las alarmas para acudir a un veterinario.<\/li>\n<\/ul>\n<p>\u00a0<\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Nuestras mascotas, al igual que nosotros, sufren enfermedades o infecciones que son necesarias atender por su seguridad. Por ello, tener un seguro para los cuidados m\u00e9dicos puede llegar a salvar la vida de tu mascota. La ataxia, por ejemplo, es una de las enfermedades m\u00e1s comunes en gatos y de la que probablemente hayas o\u00eddo &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Ataxia en gatos: qu\u00e9 es y c\u00f3mo se desarrolla esta enfermedad\" class=\"read-more button\" href=\"\/blog\/salud\/ataxia-en-gatos-que-es-y-como-se-desarrolla-esta-enfermedad\/#more-7964\" aria-label=\"Leer m\u00e1s sobre Ataxia en gatos: qu\u00e9 es y c\u00f3mo se desarrolla esta enfermedad\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":8,"featured_media":7968,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","om_disable_all_campaigns":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"twitterCardType":"","cardImageID":0,"cardImage":"","cardTitle":"","cardDesc":"","cardImageAlt":"","cardPlayer":"","cardPlayerWidth":0,"cardPlayerHeight":0,"cardPlayerStream":"","cardPlayerCodec":"","footnotes":""},"categories":[3],"tags":[],"aioseo_notices":[],"featured_image_src":"\/blog\/wp-content\/uploads\/2020\/08\/Ataxia-en-gatos.jpg","featured_image_src_square":"\/blog\/wp-content\/uploads\/2020\/08\/Ataxia-en-gatos.jpg","author_info":{"display_name":"ASISA","author_link":"\/blog\/author\/laragsoto\/"},"_links":{"self":[{"href":"\/blog\/wp-json\/wp\/v2\/posts\/7964"}],"collection":[{"href":"\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"\/blog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"\/blog\/wp-json\/wp\/v2\/comments?post=7964"}],"version-history":[{"count":5,"href":"\/blog\/wp-json\/wp\/v2\/posts\/7964\/revisions"}],"predecessor-version":[{"id":7970,"href":"\/blog\/wp-json\/wp\/v2\/posts\/7964\/revisions\/7970"}],"wp:featuredmedia":[{"embeddable":true,"href":"\/blog\/wp-json\/wp\/v2\/media\/7968"}],"wp:attachment":[{"href":"\/blog\/wp-json\/wp\/v2\/media?parent=7964"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"\/blog\/wp-json\/wp\/v2\/categories?post=7964"},{"taxonomy":"post_tag","embeddable":true,"href":"\/blog\/wp-json\/wp\/v2\/tags?post=7964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}